{"id":199485,"date":"2019-08-20T12:59:34","date_gmt":"2019-08-20T11:59:34","guid":{"rendered":"https:\/\/www.stormshield.com\/?post_type=ressourcescenter&#038;p=199485"},"modified":"2022-05-02T13:12:56","modified_gmt":"2022-05-02T12:12:56","slug":"infographie-top-5-des-cyberattaques-les-plus-dangereuses-pour-les-industries","status":"publish","type":"ressourcescenter","link":"https:\/\/www.stormshield.com\/fr\/ressourcescenter\/infographie-top-5-des-cyberattaques-les-plus-dangereuses-pour-les-industries\/","title":{"rendered":"Top 5 des cyberattaques les plus dangereuses pour les industries"},"content":{"rendered":"<p>Au-del\u00e0 des pertes financi\u00e8res qu\u2019elles engendrent, les cyberattaques industrielles sont redout\u00e9es car elles pr\u00e9sentent un risque pour l\u2019environnement, les vies humaines voir la souverainet\u00e9 du pays impact\u00e9. Retour en <strong>infographie<\/strong> sur les cinq menaces les plus dangereuses qu\u2019ait connues l\u2019industrie \u00e0 ce jour \u2013 ou presque.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Au-del\u00e0 des pertes financi\u00e8res qu\u2019elles engendrent, les cyberattaques industrielles sont redout\u00e9es car elles pr\u00e9sentent un risque pour l\u2019environnement, les vies humaines voir la souverainet\u00e9 du pays impact\u00e9. Retour en infographie sur les cinq menaces les plus dangereuses qu\u2019ait connues l\u2019industrie \u00e0 ce jour \u2013 ou&#8230;<\/p>\n","protected":false},"featured_media":199486,"template":"","meta":{"_acf_changed":false,"footnotes":""},"business_size":[682,683,681],"industry":[699],"help_mefind":[],"features":[],"rc_type":[726],"type_security":[758],"maintenance":[],"offer":[],"administration_tools":[],"cloud_offers":[],"listing_product":[],"class_list":["post-199485","ressourcescenter","type-ressourcescenter","status-publish","has-post-thumbnail","hentry","business_size-eti","business_size-grande-entreprise","business_size-pme","industry-industrie-fr","rc_type-infographie","type_security-reseaux"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Top 5 des cyberattaques les plus dangereuses pour les industries - Stormshield<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.stormshield.com\/fr\/ressourcescenter\/infographie-top-5-des-cyberattaques-les-plus-dangereuses-pour-les-industries\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Top 5 des cyberattaques les plus dangereuses pour les industries - Stormshield\" \/>\n<meta property=\"og:description\" content=\"Au-del\u00e0 des pertes financi\u00e8res qu\u2019elles engendrent, les cyberattaques industrielles sont redout\u00e9es car elles pr\u00e9sentent un risque pour l\u2019environnement, les vies humaines voir la souverainet\u00e9 du pays impact\u00e9. Retour en infographie sur les cinq menaces les plus dangereuses qu\u2019ait connues l\u2019industrie \u00e0 ce jour \u2013 ou...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.stormshield.com\/fr\/ressourcescenter\/infographie-top-5-des-cyberattaques-les-plus-dangereuses-pour-les-industries\/\" \/>\n<meta property=\"og:site_name\" content=\"Stormshield\" \/>\n<meta property=\"article:modified_time\" content=\"2022-05-02T12:12:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.stormshield.com\/wp-content\/uploads\/capture2-9.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1191\" \/>\n\t<meta property=\"og:image:height\" content=\"787\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Stormshield\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.stormshield.com\\\/fr\\\/ressourcescenter\\\/infographie-top-5-des-cyberattaques-les-plus-dangereuses-pour-les-industries\\\/\",\"url\":\"https:\\\/\\\/www.stormshield.com\\\/fr\\\/ressourcescenter\\\/infographie-top-5-des-cyberattaques-les-plus-dangereuses-pour-les-industries\\\/\",\"name\":\"Top 5 des cyberattaques les plus dangereuses pour les industries - Stormshield\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.stormshield.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.stormshield.com\\\/fr\\\/ressourcescenter\\\/infographie-top-5-des-cyberattaques-les-plus-dangereuses-pour-les-industries\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.stormshield.com\\\/fr\\\/ressourcescenter\\\/infographie-top-5-des-cyberattaques-les-plus-dangereuses-pour-les-industries\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.stormshield.com\\\/wp-content\\\/uploads\\\/capture2-9.jpg\",\"datePublished\":\"2019-08-20T11:59:34+00:00\",\"dateModified\":\"2022-05-02T12:12:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.stormshield.com\\\/fr\\\/ressourcescenter\\\/infographie-top-5-des-cyberattaques-les-plus-dangereuses-pour-les-industries\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.stormshield.com\\\/fr\\\/ressourcescenter\\\/infographie-top-5-des-cyberattaques-les-plus-dangereuses-pour-les-industries\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.stormshield.com\\\/fr\\\/ressourcescenter\\\/infographie-top-5-des-cyberattaques-les-plus-dangereuses-pour-les-industries\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.stormshield.com\\\/wp-content\\\/uploads\\\/capture2-9.jpg\",\"contentUrl\":\"https:\\\/\\\/www.stormshield.com\\\/wp-content\\\/uploads\\\/capture2-9.jpg\",\"width\":1191,\"height\":787},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.stormshield.com\\\/fr\\\/ressourcescenter\\\/infographie-top-5-des-cyberattaques-les-plus-dangereuses-pour-les-industries\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.stormshield.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Resources center\",\"item\":\"https:\\\/\\\/www.stormshield.com\\\/fr\\\/ressourcescenter\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Top 5 des cyberattaques les plus dangereuses pour les industries\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.stormshield.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.stormshield.com\\\/fr\\\/\",\"name\":\"Stormshield\",\"description\":\"Stormshield\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.stormshield.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Top 5 des cyberattaques les plus dangereuses pour les industries - Stormshield","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.stormshield.com\/fr\/ressourcescenter\/infographie-top-5-des-cyberattaques-les-plus-dangereuses-pour-les-industries\/","og_locale":"fr_FR","og_type":"article","og_title":"Top 5 des cyberattaques les plus dangereuses pour les industries - Stormshield","og_description":"Au-del\u00e0 des pertes financi\u00e8res qu\u2019elles engendrent, les cyberattaques industrielles sont redout\u00e9es car elles pr\u00e9sentent un risque pour l\u2019environnement, les vies humaines voir la souverainet\u00e9 du pays impact\u00e9. Retour en infographie sur les cinq menaces les plus dangereuses qu\u2019ait connues l\u2019industrie \u00e0 ce jour \u2013 ou...","og_url":"https:\/\/www.stormshield.com\/fr\/ressourcescenter\/infographie-top-5-des-cyberattaques-les-plus-dangereuses-pour-les-industries\/","og_site_name":"Stormshield","article_modified_time":"2022-05-02T12:12:56+00:00","og_image":[{"width":1191,"height":787,"url":"https:\/\/www.stormshield.com\/wp-content\/uploads\/capture2-9.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@Stormshield","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.stormshield.com\/fr\/ressourcescenter\/infographie-top-5-des-cyberattaques-les-plus-dangereuses-pour-les-industries\/","url":"https:\/\/www.stormshield.com\/fr\/ressourcescenter\/infographie-top-5-des-cyberattaques-les-plus-dangereuses-pour-les-industries\/","name":"Top 5 des cyberattaques les plus dangereuses pour les industries - Stormshield","isPartOf":{"@id":"https:\/\/www.stormshield.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.stormshield.com\/fr\/ressourcescenter\/infographie-top-5-des-cyberattaques-les-plus-dangereuses-pour-les-industries\/#primaryimage"},"image":{"@id":"https:\/\/www.stormshield.com\/fr\/ressourcescenter\/infographie-top-5-des-cyberattaques-les-plus-dangereuses-pour-les-industries\/#primaryimage"},"thumbnailUrl":"https:\/\/www.stormshield.com\/wp-content\/uploads\/capture2-9.jpg","datePublished":"2019-08-20T11:59:34+00:00","dateModified":"2022-05-02T12:12:56+00:00","breadcrumb":{"@id":"https:\/\/www.stormshield.com\/fr\/ressourcescenter\/infographie-top-5-des-cyberattaques-les-plus-dangereuses-pour-les-industries\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.stormshield.com\/fr\/ressourcescenter\/infographie-top-5-des-cyberattaques-les-plus-dangereuses-pour-les-industries\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.stormshield.com\/fr\/ressourcescenter\/infographie-top-5-des-cyberattaques-les-plus-dangereuses-pour-les-industries\/#primaryimage","url":"https:\/\/www.stormshield.com\/wp-content\/uploads\/capture2-9.jpg","contentUrl":"https:\/\/www.stormshield.com\/wp-content\/uploads\/capture2-9.jpg","width":1191,"height":787},{"@type":"BreadcrumbList","@id":"https:\/\/www.stormshield.com\/fr\/ressourcescenter\/infographie-top-5-des-cyberattaques-les-plus-dangereuses-pour-les-industries\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.stormshield.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Resources center","item":"https:\/\/www.stormshield.com\/fr\/ressourcescenter\/"},{"@type":"ListItem","position":3,"name":"Top 5 des cyberattaques les plus dangereuses pour les industries"}]},{"@type":"WebSite","@id":"https:\/\/www.stormshield.com\/fr\/#website","url":"https:\/\/www.stormshield.com\/fr\/","name":"Stormshield","description":"Stormshield","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.stormshield.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/www.stormshield.com\/fr\/wp-json\/wp\/v2\/ressourcescenter\/199485","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.stormshield.com\/fr\/wp-json\/wp\/v2\/ressourcescenter"}],"about":[{"href":"https:\/\/www.stormshield.com\/fr\/wp-json\/wp\/v2\/types\/ressourcescenter"}],"version-history":[{"count":1,"href":"https:\/\/www.stormshield.com\/fr\/wp-json\/wp\/v2\/ressourcescenter\/199485\/revisions"}],"predecessor-version":[{"id":199487,"href":"https:\/\/www.stormshield.com\/fr\/wp-json\/wp\/v2\/ressourcescenter\/199485\/revisions\/199487"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.stormshield.com\/fr\/wp-json\/wp\/v2\/media\/199486"}],"wp:attachment":[{"href":"https:\/\/www.stormshield.com\/fr\/wp-json\/wp\/v2\/media?parent=199485"}],"wp:term":[{"taxonomy":"business_size","embeddable":true,"href":"https:\/\/www.stormshield.com\/fr\/wp-json\/wp\/v2\/business_size?post=199485"},{"taxonomy":"industry","embeddable":true,"href":"https:\/\/www.stormshield.com\/fr\/wp-json\/wp\/v2\/industry?post=199485"},{"taxonomy":"help_mefind","embeddable":true,"href":"https:\/\/www.stormshield.com\/fr\/wp-json\/wp\/v2\/help_mefind?post=199485"},{"taxonomy":"features","embeddable":true,"href":"https:\/\/www.stormshield.com\/fr\/wp-json\/wp\/v2\/features?post=199485"},{"taxonomy":"rc_type","embeddable":true,"href":"https:\/\/www.stormshield.com\/fr\/wp-json\/wp\/v2\/rc_type?post=199485"},{"taxonomy":"type_security","embeddable":true,"href":"https:\/\/www.stormshield.com\/fr\/wp-json\/wp\/v2\/type_security?post=199485"},{"taxonomy":"maintenance","embeddable":true,"href":"https:\/\/www.stormshield.com\/fr\/wp-json\/wp\/v2\/maintenance?post=199485"},{"taxonomy":"offer","embeddable":true,"href":"https:\/\/www.stormshield.com\/fr\/wp-json\/wp\/v2\/offer?post=199485"},{"taxonomy":"administration_tools","embeddable":true,"href":"https:\/\/www.stormshield.com\/fr\/wp-json\/wp\/v2\/administration_tools?post=199485"},{"taxonomy":"cloud_offers","embeddable":true,"href":"https:\/\/www.stormshield.com\/fr\/wp-json\/wp\/v2\/cloud_offers?post=199485"},{"taxonomy":"listing_product","embeddable":true,"href":"https:\/\/www.stormshield.com\/fr\/wp-json\/wp\/v2\/listing_product?post=199485"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}