{"id":673564,"date":"2025-09-26T09:00:52","date_gmt":"2025-09-26T08:00:52","guid":{"rendered":"https:\/\/www.stormshield.com\/?p=673564"},"modified":"2025-09-26T09:35:49","modified_gmt":"2025-09-26T08:35:49","slug":"nomination-bertrand-trastour-head-of-global-sales","status":"publish","type":"post","link":"https:\/\/www.stormshield.com\/fr\/actus\/nomination-bertrand-trastour-head-of-global-sales\/","title":{"rendered":"Stormshield nomme Bertrand Trastour au poste de Head of Global Sales"},"content":{"rendered":"<p><strong>Stormshield\u00a0annonce la nomination de Bertrand Trastour en tant que Head of Global Sales, afin de piloter la strat\u00e9gie de croissance de l\u2019entreprise et renforcer la position de Stormshield en tant qu\u2019acteur majeur de la cybers\u00e9curit\u00e9 en Europe et dans le monde.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<h2>Une expertise cyber reconnue et \u00e9prouv\u00e9e<\/h2>\n<p>Pr\u00e9c\u00e9demment directeur g\u00e9n\u00e9ral France, Afrique du Nord, de l\u2019ouest et centrale chez Kaspersky, <strong>Bertrand Trastour<\/strong> prend la direction des \u00e9quipes commerciales et avant-ventes, fort de 30 ann\u00e9es d\u2019exp\u00e9rience en ventes et management dans le secteur de la cybersecurit\u00e9. Dans ses nouvelles fonctions, il apportera sa connaissance du march\u00e9, des strat\u00e9gies commerciales et de management de r\u00e9seaux de partenaires distributeurs et int\u00e9grateurs. Dipl\u00f4m\u00e9 de l\u2019IHEDN et d\u2019Audencia Business School, son parcours l\u2019am\u00e8ne \u00e0 occuper des postes d\u2019ing\u00e9nieur commercial et de responsable des ventes chez Arkoon, Citrix Systems, Avanquest Software ou Asap Software.<\/p>\n<p>En 2013, il rejoint Kaspersky, en tant que responsable des ventes grands comptes, puis est nomm\u00e9 directeur des ventes B2B en 2018. Depuis le 1er janvier 2021, il occupait le poste de directeur g\u00e9n\u00e9ral de Kaspersky France, Afrique du Nord, de l\u2019Ouest et Centrale.<\/p>\n<p>\u00ab\u00a0<em>Nous sommes ravis de l\u2019arriv\u00e9e de Bertrand Trastour chez Stormshield au poste de Head of Global Sales et membre du Comit\u00e9 Ex\u00e9cutif<\/em>, d\u00e9clare <strong>Pierre-Yves Hentzen<\/strong>, CEO de Stormshield. <em>Bertrand va nous apporter son exp\u00e9rience, son dynamisme et une culture du terrain qui renforcera la proximit\u00e9 avec nos clients utilisateurs et partenaires.\u00a0\u00bb<\/em><\/p>\n<p>&nbsp;<\/p>\n<h2>La satisfaction client au c\u0153ur de la strat\u00e9gie<\/h2>\n<p>Dans le cadre de ses diff\u00e9rentes fonctions, <a href=\"https:\/\/www.linkedin.com\/in\/bertrandtrastour\/\" target=\"_blank\" rel=\"noopener\">Bertrand Trastour<\/a> prendra une part active \u00e0 la strat\u00e9gie de croissance de Stormshield, en mettant au premier plan la satisfaction des clients au travers de solutions adapt\u00e9es \u00e0 leurs probl\u00e9matiques de s\u00e9curit\u00e9.<\/p>\n<p><em>\u00ab\u00a0Dans un paysage cyber marqu\u00e9 par des attaques polymorphes dont le nombre est en croissance exponentielle et un cyber-espace qui se fragmente, la confiance, la r\u00e9silience et la souverainet\u00e9 num\u00e9rique doivent \u00eatre plus que jamais au c\u0153ur des choix strat\u00e9giques des entreprises et institutions europ\u00e9ennes\u00a0\u00bb<\/em>, ajoute Bertrand Trastour.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Stormshield\u00a0annonce la nomination de Bertrand Trastour en tant que Head of Global Sales, afin de piloter la strat\u00e9gie de croissance de l\u2019entreprise et renforcer la position de Stormshield en tant qu\u2019acteur majeur de la cybers\u00e9curit\u00e9 en Europe et dans le monde. &nbsp; Une expertise cyber&#8230;<\/p>\n","protected":false},"author":6,"featured_media":673565,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[2],"tags":[4362],"business_size":[],"industry":[],"help_mefind":[],"features":[],"type_security":[],"maintenance":[],"offer":[],"administration_tools":[],"cloud_offers":[],"listing_product":[],"class_list":["post-673564","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-corporate-fr","tag-vie-entreprise"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nomination de Bertrand Trastour Head of Global Sales<\/title>\n<meta name=\"description\" content=\"Bertrand Trastour prend la direction des \u00e9quipes commerciales &amp; avant-ventes et une part active \u00e0 la strat\u00e9gie de croissance de Stormshield.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.stormshield.com\/fr\/actus\/nomination-bertrand-trastour-head-of-global-sales\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nomination de Bertrand Trastour Head of Global Sales\" \/>\n<meta property=\"og:description\" content=\"Bertrand Trastour prend la direction des \u00e9quipes commerciales &amp; avant-ventes et une part active \u00e0 la strat\u00e9gie de croissance de Stormshield.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.stormshield.com\/fr\/actus\/nomination-bertrand-trastour-head-of-global-sales\/\" \/>\n<meta property=\"og:site_name\" content=\"Stormshield\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-26T08:00:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-26T08:35:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.stormshield.com\/wp-content\/uploads\/btr-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"480\" \/>\n\t<meta property=\"og:image:height\" content=\"480\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Karine Monmarch\u00e9\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Stormshield\" \/>\n<meta name=\"twitter:site\" content=\"@Stormshield\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Karine Monmarch\u00e9\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.stormshield.com\\\/fr\\\/actus\\\/nomination-bertrand-trastour-head-of-global-sales\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.stormshield.com\\\/fr\\\/actus\\\/nomination-bertrand-trastour-head-of-global-sales\\\/\"},\"author\":{\"name\":\"Karine Monmarch\u00e9\",\"@id\":\"https:\\\/\\\/www.stormshield.com\\\/fr\\\/#\\\/schema\\\/person\\\/574a736090056941fdfbaec515742df2\"},\"headline\":\"Stormshield nomme Bertrand Trastour au poste de Head of Global Sales\",\"datePublished\":\"2025-09-26T08:00:52+00:00\",\"dateModified\":\"2025-09-26T08:35:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.stormshield.com\\\/fr\\\/actus\\\/nomination-bertrand-trastour-head-of-global-sales\\\/\"},\"wordCount\":379,\"image\":{\"@id\":\"https:\\\/\\\/www.stormshield.com\\\/fr\\\/actus\\\/nomination-bertrand-trastour-head-of-global-sales\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.stormshield.com\\\/wp-content\\\/uploads\\\/btr-2.jpg\",\"keywords\":[\"Vie de l'entreprise\"],\"articleSection\":[\"Corporate\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.stormshield.com\\\/fr\\\/actus\\\/nomination-bertrand-trastour-head-of-global-sales\\\/\",\"url\":\"https:\\\/\\\/www.stormshield.com\\\/fr\\\/actus\\\/nomination-bertrand-trastour-head-of-global-sales\\\/\",\"name\":\"Nomination de Bertrand Trastour Head of Global Sales\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.stormshield.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.stormshield.com\\\/fr\\\/actus\\\/nomination-bertrand-trastour-head-of-global-sales\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.stormshield.com\\\/fr\\\/actus\\\/nomination-bertrand-trastour-head-of-global-sales\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.stormshield.com\\\/wp-content\\\/uploads\\\/btr-2.jpg\",\"datePublished\":\"2025-09-26T08:00:52+00:00\",\"dateModified\":\"2025-09-26T08:35:49+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.stormshield.com\\\/fr\\\/#\\\/schema\\\/person\\\/574a736090056941fdfbaec515742df2\"},\"description\":\"Bertrand Trastour prend la direction des \u00e9quipes commerciales & avant-ventes et une part active \u00e0 la strat\u00e9gie de croissance de Stormshield.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.stormshield.com\\\/fr\\\/actus\\\/nomination-bertrand-trastour-head-of-global-sales\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.stormshield.com\\\/fr\\\/actus\\\/nomination-bertrand-trastour-head-of-global-sales\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.stormshield.com\\\/fr\\\/actus\\\/nomination-bertrand-trastour-head-of-global-sales\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.stormshield.com\\\/wp-content\\\/uploads\\\/btr-2.jpg\",\"contentUrl\":\"https:\\\/\\\/www.stormshield.com\\\/wp-content\\\/uploads\\\/btr-2.jpg\",\"width\":480,\"height\":480},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.stormshield.com\\\/fr\\\/actus\\\/nomination-bertrand-trastour-head-of-global-sales\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.stormshield.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Stormshield nomme Bertrand Trastour au poste de Head of Global Sales\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.stormshield.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.stormshield.com\\\/fr\\\/\",\"name\":\"Stormshield\",\"description\":\"Stormshield\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.stormshield.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.stormshield.com\\\/fr\\\/#\\\/schema\\\/person\\\/574a736090056941fdfbaec515742df2\",\"name\":\"Karine Monmarch\u00e9\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1b346f69bf26fb6cf21d0401833d3bc0b14e62d80280ca0ceebb5cb704994220?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1b346f69bf26fb6cf21d0401833d3bc0b14e62d80280ca0ceebb5cb704994220?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1b346f69bf26fb6cf21d0401833d3bc0b14e62d80280ca0ceebb5cb704994220?s=96&d=mm&r=g\",\"caption\":\"Karine Monmarch\u00e9\"},\"description\":\"Karine is Global Lead Marketing at Stormshield. Her multi-expertise background includes marketing and communication in all their guises. Well-versed in strategic and service offer marketing, in external, internal, Web &amp; editorial communication, she has dedicated her career to exploring the areas she is passionate about: energy and new technologies in the broadest possible sense.\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nomination de Bertrand Trastour Head of Global Sales","description":"Bertrand Trastour prend la direction des \u00e9quipes commerciales & avant-ventes et une part active \u00e0 la strat\u00e9gie de croissance de Stormshield.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.stormshield.com\/fr\/actus\/nomination-bertrand-trastour-head-of-global-sales\/","og_locale":"fr_FR","og_type":"article","og_title":"Nomination de Bertrand Trastour Head of Global Sales","og_description":"Bertrand Trastour prend la direction des \u00e9quipes commerciales & avant-ventes et une part active \u00e0 la strat\u00e9gie de croissance de Stormshield.","og_url":"https:\/\/www.stormshield.com\/fr\/actus\/nomination-bertrand-trastour-head-of-global-sales\/","og_site_name":"Stormshield","article_published_time":"2025-09-26T08:00:52+00:00","article_modified_time":"2025-09-26T08:35:49+00:00","og_image":[{"width":480,"height":480,"url":"https:\/\/www.stormshield.com\/wp-content\/uploads\/btr-2.jpg","type":"image\/jpeg"}],"author":"Karine Monmarch\u00e9","twitter_card":"summary_large_image","twitter_creator":"@Stormshield","twitter_site":"@Stormshield","twitter_misc":{"\u00c9crit par":"Karine Monmarch\u00e9","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.stormshield.com\/fr\/actus\/nomination-bertrand-trastour-head-of-global-sales\/#article","isPartOf":{"@id":"https:\/\/www.stormshield.com\/fr\/actus\/nomination-bertrand-trastour-head-of-global-sales\/"},"author":{"name":"Karine Monmarch\u00e9","@id":"https:\/\/www.stormshield.com\/fr\/#\/schema\/person\/574a736090056941fdfbaec515742df2"},"headline":"Stormshield nomme Bertrand Trastour au poste de Head of Global Sales","datePublished":"2025-09-26T08:00:52+00:00","dateModified":"2025-09-26T08:35:49+00:00","mainEntityOfPage":{"@id":"https:\/\/www.stormshield.com\/fr\/actus\/nomination-bertrand-trastour-head-of-global-sales\/"},"wordCount":379,"image":{"@id":"https:\/\/www.stormshield.com\/fr\/actus\/nomination-bertrand-trastour-head-of-global-sales\/#primaryimage"},"thumbnailUrl":"https:\/\/www.stormshield.com\/wp-content\/uploads\/btr-2.jpg","keywords":["Vie de l'entreprise"],"articleSection":["Corporate"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.stormshield.com\/fr\/actus\/nomination-bertrand-trastour-head-of-global-sales\/","url":"https:\/\/www.stormshield.com\/fr\/actus\/nomination-bertrand-trastour-head-of-global-sales\/","name":"Nomination de Bertrand Trastour Head of Global Sales","isPartOf":{"@id":"https:\/\/www.stormshield.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.stormshield.com\/fr\/actus\/nomination-bertrand-trastour-head-of-global-sales\/#primaryimage"},"image":{"@id":"https:\/\/www.stormshield.com\/fr\/actus\/nomination-bertrand-trastour-head-of-global-sales\/#primaryimage"},"thumbnailUrl":"https:\/\/www.stormshield.com\/wp-content\/uploads\/btr-2.jpg","datePublished":"2025-09-26T08:00:52+00:00","dateModified":"2025-09-26T08:35:49+00:00","author":{"@id":"https:\/\/www.stormshield.com\/fr\/#\/schema\/person\/574a736090056941fdfbaec515742df2"},"description":"Bertrand Trastour prend la direction des \u00e9quipes commerciales & avant-ventes et une part active \u00e0 la strat\u00e9gie de croissance de Stormshield.","breadcrumb":{"@id":"https:\/\/www.stormshield.com\/fr\/actus\/nomination-bertrand-trastour-head-of-global-sales\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.stormshield.com\/fr\/actus\/nomination-bertrand-trastour-head-of-global-sales\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.stormshield.com\/fr\/actus\/nomination-bertrand-trastour-head-of-global-sales\/#primaryimage","url":"https:\/\/www.stormshield.com\/wp-content\/uploads\/btr-2.jpg","contentUrl":"https:\/\/www.stormshield.com\/wp-content\/uploads\/btr-2.jpg","width":480,"height":480},{"@type":"BreadcrumbList","@id":"https:\/\/www.stormshield.com\/fr\/actus\/nomination-bertrand-trastour-head-of-global-sales\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.stormshield.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Stormshield nomme Bertrand Trastour au poste de Head of Global Sales"}]},{"@type":"WebSite","@id":"https:\/\/www.stormshield.com\/fr\/#website","url":"https:\/\/www.stormshield.com\/fr\/","name":"Stormshield","description":"Stormshield","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.stormshield.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.stormshield.com\/fr\/#\/schema\/person\/574a736090056941fdfbaec515742df2","name":"Karine Monmarch\u00e9","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/1b346f69bf26fb6cf21d0401833d3bc0b14e62d80280ca0ceebb5cb704994220?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/1b346f69bf26fb6cf21d0401833d3bc0b14e62d80280ca0ceebb5cb704994220?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1b346f69bf26fb6cf21d0401833d3bc0b14e62d80280ca0ceebb5cb704994220?s=96&d=mm&r=g","caption":"Karine Monmarch\u00e9"},"description":"Karine is Global Lead Marketing at Stormshield. Her multi-expertise background includes marketing and communication in all their guises. Well-versed in strategic and service offer marketing, in external, internal, Web &amp; editorial communication, she has dedicated her career to exploring the areas she is passionate about: energy and new technologies in the broadest possible sense."}]}},"_links":{"self":[{"href":"https:\/\/www.stormshield.com\/fr\/wp-json\/wp\/v2\/posts\/673564","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.stormshield.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.stormshield.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.stormshield.com\/fr\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.stormshield.com\/fr\/wp-json\/wp\/v2\/comments?post=673564"}],"version-history":[{"count":1,"href":"https:\/\/www.stormshield.com\/fr\/wp-json\/wp\/v2\/posts\/673564\/revisions"}],"predecessor-version":[{"id":673570,"href":"https:\/\/www.stormshield.com\/fr\/wp-json\/wp\/v2\/posts\/673564\/revisions\/673570"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.stormshield.com\/fr\/wp-json\/wp\/v2\/media\/673565"}],"wp:attachment":[{"href":"https:\/\/www.stormshield.com\/fr\/wp-json\/wp\/v2\/media?parent=673564"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.stormshield.com\/fr\/wp-json\/wp\/v2\/categories?post=673564"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.stormshield.com\/fr\/wp-json\/wp\/v2\/tags?post=673564"},{"taxonomy":"business_size","embeddable":true,"href":"https:\/\/www.stormshield.com\/fr\/wp-json\/wp\/v2\/business_size?post=673564"},{"taxonomy":"industry","embeddable":true,"href":"https:\/\/www.stormshield.com\/fr\/wp-json\/wp\/v2\/industry?post=673564"},{"taxonomy":"help_mefind","embeddable":true,"href":"https:\/\/www.stormshield.com\/fr\/wp-json\/wp\/v2\/help_mefind?post=673564"},{"taxonomy":"features","embeddable":true,"href":"https:\/\/www.stormshield.com\/fr\/wp-json\/wp\/v2\/features?post=673564"},{"taxonomy":"type_security","embeddable":true,"href":"https:\/\/www.stormshield.com\/fr\/wp-json\/wp\/v2\/type_security?post=673564"},{"taxonomy":"maintenance","embeddable":true,"href":"https:\/\/www.stormshield.com\/fr\/wp-json\/wp\/v2\/maintenance?post=673564"},{"taxonomy":"offer","embeddable":true,"href":"https:\/\/www.stormshield.com\/fr\/wp-json\/wp\/v2\/offer?post=673564"},{"taxonomy":"administration_tools","embeddable":true,"href":"https:\/\/www.stormshield.com\/fr\/wp-json\/wp\/v2\/administration_tools?post=673564"},{"taxonomy":"cloud_offers","embeddable":true,"href":"https:\/\/www.stormshield.com\/fr\/wp-json\/wp\/v2\/cloud_offers?post=673564"},{"taxonomy":"listing_product","embeddable":true,"href":"https:\/\/www.stormshield.com\/fr\/wp-json\/wp\/v2\/listing_product?post=673564"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}